{"id":11573,"date":"2017-05-15T20:23:56","date_gmt":"2017-05-16T00:23:56","guid":{"rendered":"http:\/\/www.rincondelbulla.cl\/portal\/?p=11573"},"modified":"2017-05-15T20:44:24","modified_gmt":"2017-05-16T00:44:24","slug":"se-viene-la-venta-de-entradas-y-mas-caras","status":"publish","type":"post","link":"http:\/\/www.rincondelbulla.cl\/portal\/2017\/05\/15\/se-viene-la-venta-de-entradas-y-mas-caras\/","title":{"rendered":"Se viene la venta de entradas&#8230; y m\u00e1s caras"},"content":{"rendered":"<p><strong>Pese a la pol\u00edtica de reducci\u00f3n de precios, la situaci\u00f3n en que se encuentra la \u00abU\u00bb fue el motivo de una alza en el valor de las entradas.<\/strong><!--more--><\/p>\n<p>8 mil pesos costar\u00e1 la galer\u00eda, valor que aumentar\u00e1 en todas las localidades del estadio para el partido de este s\u00e1bado frente a San Luis de Quillota, al que los azules llegan con la primera opci\u00f3n del t\u00edtulo.<\/p>\n<p>La venta de entradas comenzar\u00e1 hoy pasada las 22 horas y tendr\u00e1 una base de datos que solo permitir\u00e1 la compra de quienes hayan adquirido alg\u00fan ticket para ver a los azules de local durante el 2017. Esta solo se liberar\u00e1 para p\u00fablico general el jueves.<\/p>\n<p>El encuentro a disputarse este s\u00e1bado en el Estadio Nacional espera tener\u00a0un aforo completo, es decir, habr\u00edan 48.665 tickets a disposici\u00f3n.<\/p>\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p dir=\"ltr\" lang=\"es\">Informaci\u00f3n importante respecto a la venta de entradas para el partido de este s\u00e1bado! <a href=\"https:\/\/twitter.com\/hashtag\/VamosLaU?src=hash\">#VamosLaU<\/a> <a href=\"https:\/\/t.co\/HfeKomRc2w\">pic.twitter.com\/HfeKomRc2w<\/a><\/p>\n<p>\u2014 Universidad de Chile (@udechile) <a href=\"https:\/\/twitter.com\/udechile\/status\/864257976575696898\">15 de mayo de 2017<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pese a la pol\u00edtica de reducci\u00f3n de precios, la situaci\u00f3n en que se encuentra la \u00abU\u00bb fue el motivo de una alza en el valor de las entradas.<\/p>\n","protected":false},"author":65,"featured_media":11366,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[195,841,294],"class_list":{"0":"post-11573","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"tag-entradas","9":"tag-san-luis","10":"tag-u-de-chile"},"_links":{"self":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/11573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/comments?post=11573"}],"version-history":[{"count":5,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/11573\/revisions"}],"predecessor-version":[{"id":11579,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/11573\/revisions\/11579"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/media\/11366"}],"wp:attachment":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/media?parent=11573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/categories?post=11573"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/tags?post=11573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}