{"id":12461,"date":"2017-08-31T10:44:51","date_gmt":"2017-08-31T14:44:51","guid":{"rendered":"http:\/\/www.rincondelbulla.cl\/portal\/?p=12461"},"modified":"2017-08-31T10:44:51","modified_gmt":"2017-08-31T14:44:51","slug":"pinilla-el-equipo-no-se-esta-cayendo","status":"publish","type":"post","link":"http:\/\/www.rincondelbulla.cl\/portal\/2017\/08\/31\/pinilla-el-equipo-no-se-esta-cayendo\/","title":{"rendered":"Pinilla: \u00abEl equipo no se est\u00e1 cayendo\u00bb"},"content":{"rendered":"<figure id=\"attachment_12053\" aria-describedby=\"caption-attachment-12053\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-12053\" src=\"http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/08\/Mauricio-Pinilla-post-Temuco.jpeg\" alt=\"\" width=\"1000\" height=\"667\" srcset=\"http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/08\/Mauricio-Pinilla-post-Temuco.jpeg 1000w, http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/08\/Mauricio-Pinilla-post-Temuco-300x200.jpeg 300w, http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/08\/Mauricio-Pinilla-post-Temuco-768x512.jpeg 768w, http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/08\/Mauricio-Pinilla-post-Temuco-696x464.jpeg 696w, http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/08\/Mauricio-Pinilla-post-Temuco-630x420.jpeg 630w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-12053\" class=\"wp-caption-text\">Fotograf\u00eda: Claudio C\u00e1ceres<\/figcaption><\/figure>\n<p><strong>Mauricio Pinilla, exterioriz\u00f3 su satisfacci\u00f3n por el buen desempe\u00f1o del cuadro azul en el claro triunfo a domicilio por 3-0 sobre Audax Italiano.<\/strong><\/p>\n<p>Tras el pitazo final en el Estadio Bicentenario de La Florida, declar\u00f3 que \u201cno hay mejorar forma de reponerse que con una victoria. El equipo mostr\u00f3 un car\u00e1cter muy grande para sacar adelante este partido\u00bb.<\/p>\n<p>\u2018Pinigol\u2019 se matricul\u00f3 en la presente jornada con un doblete, sumando tres dianas en los \u00faltimos dos encuentros con la \u2018U\u2019. \u00abNo hay mejor confianza para un delantero que marcar. Mis compa\u00f1eros me asistieron de gran forma y pude marcar dos goles para tener ventaja para la vuelta\u00bb, dijo.<\/p>\n<p>Para finalizar, el experimentado atacante se\u00f1al\u00f3 que \u00abesto es la \u2018U\u2019 y estoy feliz de estar ac\u00e1. Lo primordial era hacer un lindo partido despu\u00e9s de una derrota fea. El equipo no se est\u00e1 cayendo\u00bb.<\/p>\n<p>De esta manera, el actual campe\u00f3n del balompi\u00e9 nacional dej\u00f3 pr\u00e1cticamente encaminada la llave, que culminar\u00e1 el s\u00e1bado 2 de septiembre en el Estadio Nacional, y buscar\u00e1 ahora enfocarse en el Transici\u00f3n, donde es quinto con nueve puntos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mauricio Pinilla, exterioriz\u00f3 su satisfacci\u00f3n por el buen desempe\u00f1o del cuadro azul en el claro triunfo a domicilio por 3-0 sobre Audax Italiano. Tras el pitazo final en el Estadio Bicentenario de La Florida, declar\u00f3 que \u201cno hay mejorar forma de reponerse que con una victoria. El equipo mostr\u00f3 un car\u00e1cter muy grande para sacar [&#8230;]<\/p>\n","protected":false},"author":21395,"featured_media":12053,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[454,1116,631,156],"class_list":{"0":"post-12461","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"tag-actualidad","9":"tag-cuadro-magico","10":"tag-mauricio-pinilla","11":"tag-universidad-de-chile"},"_links":{"self":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/12461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/users\/21395"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/comments?post=12461"}],"version-history":[{"count":1,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/12461\/revisions"}],"predecessor-version":[{"id":12462,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/12461\/revisions\/12462"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/media\/12053"}],"wp:attachment":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/media?parent=12461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/categories?post=12461"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/tags?post=12461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}