{"id":143,"date":"2007-07-12T15:41:19","date_gmt":"2007-07-12T15:41:19","guid":{"rendered":"http:\/\/www.rincondelbulla.cl\/portal\/?p=143"},"modified":"2007-07-12T15:41:19","modified_gmt":"2007-07-12T15:41:19","slug":"se-arma-el-esqueleto-la-llegada-de-un-delantero-es-el-gran-objetivo-de-la-u","status":"publish","type":"post","link":"http:\/\/www.rincondelbulla.cl\/portal\/2007\/07\/12\/se-arma-el-esqueleto-la-llegada-de-un-delantero-es-el-gran-objetivo-de-la-u\/","title":{"rendered":"Se arma el esqueleto: La llegada de un delantero es el gran objetivo de la \u00abU\u00bb"},"content":{"rendered":"<p><img decoding=\"async\" src=\"images\/stories\/plantel2.jpg\" hspace=\"6\" alt=\"\" title=\"\" border=\"0\" style=\"float: left;\" \/><strong>Con la llegada de Mariano Puyol, H&eacute;ctor Hoffens y Vladimir Bigorra a las divisiones inferiores, Azul Azul complet&oacute; el staff t&eacute;cnico solicitado por Arturo Salah a su llegada.<\/strong><br \/>Est&aacute; listo. Azul Azul se propuso como prioridad para su gesti&oacute;n dejar funcionando el &aacute;rea t&eacute;cnica lo antes posible, a expresa petici&oacute;n del entrenador Arturo Salah.<\/p>\n<p> <!--more--> <\/p>\n<p>Cuando el ex DT de Huachipato lleg&oacute; al club s&oacute;lo quedaban dos entrenadores para las divisiones inferiores (Cristi&aacute;n Mora y Hugo Vilches), pues Cristi&aacute;n Romero fue destinado al primer equipo (hoy es el ayudante del ex seleccionador nacional) y Ronald Fuentes se fue a Melipilla para iniciar su carrera como estratega de Primera Divisi&oacute;n.<\/p>\n<p>La prioridad, entonces, fue armar un nuevo equipo de trabajo. Y pensando en eso es que se eligi&oacute; a H&eacute;ctor Pinto para que asumiera la testera de cadetes.<\/p>\n<p>El &quot;Negro&quot; ten&iacute;a la misi&oacute;n de conformar dicho staff. Y esa tarea ya la cumpli&oacute;: el martes empez&oacute; a trabajar en el club su ex asistente en Uni&oacute;n Espa&ntilde;ola, Vladimir Bigorra, quien se har&aacute; cargo de la Sub 17. Tambi&eacute;n se sumaron H&eacute;ctor Hoffens, hombre muy cercano al m&aacute;ximo accionista de la concesionaria que se adjudic&oacute; la administraci&oacute;n del club (Carlos Heller), y Mariano Puyol, un hist&oacute;rico de cadetes y quien fuera ayudante de Jorge Soc&iacute;as el semestre pasado.<\/p>\n<p>Ellos, en todo caso, estar&aacute;n bajo la estricta supervisi&oacute;n de Salah, quien en el primer equipo trabaja con Romero como mano derecha y el argentino Marcelo Rosemblat como preparador f&iacute;sico.<\/p>\n<p>En cuanto a los cargos administrativos, al gerente deportivo Johnny Ashwell -quien ha estado a cargo de las contrataciones- se agregar&aacute; a fin de mes el gerente general Cristi&aacute;n Auber.<\/p>\n<p>&iquest;Y el delantero?<\/p>\n<p>Muchos dolores de cabeza ha tenido que soportar Salah en la conformaci&oacute;n del primer equipo de la U. A falta de 10 d&iacute;as para el debut en el Torneo de Clausura ante U. de Concepci&oacute;n, el club no ha podido amarrar la contrataci&oacute;n de un delantero centro argentino.<\/p>\n<p>Primero se intent&oacute; con Ezequiel Maggiolo, pero el t&eacute;cnico de Estudiantes de La Plata, Diego Simeone, fren&oacute; la operaci&oacute;n. A Ismael Blanco, de Olimpo, lo alej&oacute; su alta tasaci&oacute;n. Y Diego Ruiz, de Huachipato, ya est&aacute; descartado. &iquest;Entonces? Las fichas apuntan a Claudio Bieler (ex Atl&eacute;tico Rafaela), cuya negociaci&oacute;n con Colo Colo se entramp&oacute;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la llegada de Mariano Puyol, H&eacute;ctor Hoffens y Vladimir Bigorra a las divisiones inferiores, Azul Azul complet&oacute; el staff t&eacute;cnico solicitado por Arturo Salah a su llegada.Est&aacute; listo. Azul Azul se propuso como prioridad para su gesti&oacute;n dejar funcionando el &aacute;rea t&eacute;cnica lo antes posible, a expresa petici&oacute;n del entrenador Arturo Salah.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-143","post","type-post","status-publish","format-standard","category-actualidad"],"_links":{"self":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/comments?post=143"}],"version-history":[{"count":0,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/143\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/media?parent=143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/categories?post=143"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/tags?post=143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}