{"id":6330,"date":"2014-12-04T18:36:52","date_gmt":"2014-12-04T18:36:52","guid":{"rendered":"http:\/\/www.rincondelbulla.cl\/portal\/?p=6330"},"modified":"2016-02-25T13:41:10","modified_gmt":"2016-02-25T13:41:10","slug":"jose-rojasel-dia-domingo-hablemos-de-colo-colo-si-es-que-hay-un-partido-definitorio","status":"publish","type":"post","link":"http:\/\/www.rincondelbulla.cl\/portal\/2014\/12\/04\/jose-rojasel-dia-domingo-hablemos-de-colo-colo-si-es-que-hay-un-partido-definitorio\/","title":{"rendered":"Jos\u00e9 Rojas: \u00abEl domingo hablemos de Colo Colo si es que hay un partido definitorio\u00bb"},"content":{"rendered":"<figure id=\"attachment_6262\" aria-describedby=\"caption-attachment-6262\" style=\"width: 1100px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2014\/11\/jose_rojas3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6262\" src=\"http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2014\/11\/jose_rojas3.jpg\" alt=\"Foto: Claudio C\u00e1ceres\" width=\"1100\" height=\"700\" srcset=\"http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2014\/11\/jose_rojas3.jpg 1100w, http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2014\/11\/jose_rojas3-300x191.jpg 300w, http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2014\/11\/jose_rojas3-768x489.jpg 768w, http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2014\/11\/jose_rojas3-696x443.jpg 696w, http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2014\/11\/jose_rojas3-1068x680.jpg 1068w, http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2014\/11\/jose_rojas3-660x420.jpg 660w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/a><figcaption id=\"caption-attachment-6262\" class=\"wp-caption-text\">El Capit\u00e1n \u00abPepe\u00bb Rojas quiere cerrar todo el d\u00eda s\u00e1bado. Foto: Claudio C\u00e1ceres<\/figcaption><\/figure>\n<p><strong>Antes del asado de camarader\u00eda y a poco m\u00e1s de 48 horas del que puede ser el \u00faltimo partido del torneo, enfrent\u00f3 los micr\u00f3fono el capit\u00e1n \u201cpepe\u201d Rojas, quien asegur\u00f3 que esperan \u201cDefinir todo el S\u00e1bado\u201d<\/strong><!--more--><\/p>\n<p>Jos\u00e9 Manuel Rojas ya suma varios t\u00edtulos vistiendo los colores de \u201cla gloriosa\u201d, y est\u00e1 acostumbrado a estas instancias finales y respecto al momento y al plantel lo ve as\u00ed<strong> \u201chay muchos que es la primera vez que enfrentan esta oportunidad, es un lindo desaf\u00edo, hay otros que hemos experimentado estos momentos. Cada minuto o segundo es diferente a como se ha vivido anteriormente\u201d<\/strong> Adem\u00e1s el \u201cpepe\u201d no quiso sacar de la pelea a los de la quinta regi\u00f3n agregando \u201cLo vengo diciendo hace casi dos semanas, todos hablan de la U y Colo Colo, mientras<strong> Wanderers viene haciendo un trabajo silencioso y capaz que pueda salir campe\u00f3n. En ese sentido, todos mis respetos a su gente<\/strong>\u201d.<\/p>\n<p>Sobre el partido del S\u00e1bado, \u201cEste partido para m\u00ed es muy especial, no tienes m\u00e1s chances<strong>. Si quieres salir campe\u00f3n, hay que quemar todas las naves; m\u00e1s que un partido va a ser una guerra. \u00bfUna final?, despu\u00e9s se ver\u00e1, \u00e9ste es el partido. Hay que ir con todo para salir campe\u00f3n<\/strong>\u201d asegur\u00f3.<\/p>\n<p>En la sala de prensa del CDA muchos periodistas insist\u00edan a preguntar sobre los anteriores procesos, ante lo que el capit\u00e1n respondi\u00f3 \u00abFueron campeonatos malos. Hay que ser autocr\u00edticos en todo sentido. Tanto jugadores y por la gente que ya no est\u00e1. Hoy la sensaci\u00f3n es otra. Estamos peleando arriba y este equipo se caracteriza por eso. Este torneo es muy especial por todo lo que habia pasado anteriormente. Ser\u00eda lindo coronarlo con el t\u00edtulo\u00bb<\/p>\n<p>Y cuando fue consultado sobre un partido de definici\u00f3n el defensa contesto <strong>\u00ablo ideal ser\u00eda cerrarlo el s\u00e1bado, primero es La Calera. El d\u00eda domingo hablemos de Colo Colo si es que hay un partido definitorio<\/strong>\u00bb finalizando la conferencia en La Cisterna.<\/p>\n<p><strong>FORMACI\u00d3N CONFIRMADA<\/strong><\/p>\n<p>El \u201crom\u00e1ntico viajero\u201d ya tendr\u00eda formaci\u00f3n confirmada con el ingreso de Pereira por Martinez, este \u00faltimo lesionado con un esguince de tobillo, y la formaci\u00f3n ser\u00eda as\u00ed:\u00a0<strong>Johnny Herrera; Math\u00edas Corujo, Osvaldo Gonz\u00e1lez, Cristi\u00e1n Su\u00e1rez, Jos\u00e9 Rojas; Gonzalo Espinoza, Guzm\u00e1n Pereira, Ram\u00f3n Fern\u00e1ndez, Gustavo Lorenzetti; Gustavo Canales y Patricio Rubio.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes del asado de camarader\u00eda y a poco m\u00e1s de 48 horas del que puede ser el \u00faltimo partido del torneo, enfrent\u00f3 los micr\u00f3fono el capit\u00e1n \u201cpepe\u201d Rojas, quien asegur\u00f3 que esperan \u201cDefinir todo el S\u00e1bado\u201d<\/p>\n","protected":false},"author":21381,"featured_media":6262,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,1],"tags":[454,232,209,51],"class_list":["post-6330","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","category-sin-categoria","tag-actualidad","tag-apertura-2014-2015","tag-conferencia-de-prensa","tag-jose-rojas"],"_links":{"self":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/6330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/users\/21381"}],"replies":[{"embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/comments?post=6330"}],"version-history":[{"count":4,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/6330\/revisions"}],"predecessor-version":[{"id":6334,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/6330\/revisions\/6334"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/media\/6262"}],"wp:attachment":[{"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/media?parent=6330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/categories?post=6330"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/tags?post=6330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}