{"id":13887,"date":"2018-02-15T11:06:46","date_gmt":"2018-02-15T14:06:46","guid":{"rendered":"http:\/\/www.rincondelbulla.cl\/portal\/?p=13887"},"modified":"2018-02-15T11:09:36","modified_gmt":"2018-02-15T14:09:36","slug":"pizarro-y-la-libertadores-seria-ideal-poder-jugarla-en-santa-laura","status":"publish","type":"post","link":"https:\/\/www.rincondelbulla.cl\/portal\/2018\/02\/15\/pizarro-y-la-libertadores-seria-ideal-poder-jugarla-en-santa-laura\/","title":{"rendered":"Pizarro y la Libertadores: \u00abSer\u00eda ideal poder jugarla en Santa Laura\u00bb"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-13301\" src=\"http:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/12\/David-Pizarro.jpg\" alt=\"\" width=\"1151\" height=\"700\" srcset=\"https:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/12\/David-Pizarro.jpg 1151w, https:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/12\/David-Pizarro-300x182.jpg 300w, https:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/12\/David-Pizarro-768x467.jpg 768w, https:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/12\/David-Pizarro-696x423.jpg 696w, https:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/12\/David-Pizarro-1068x650.jpg 1068w, https:\/\/www.rincondelbulla.cl\/portal\/wp-content\/uploads\/2017\/12\/David-Pizarro-691x420.jpg 691w\" sizes=\"auto, (max-width: 1151px) 100vw, 1151px\" \/><\/p>\n<p><strong>David Pizarro manifest\u00f3 su deseo que el cuadro azul sea local durante la Copa Libertadores 2018 en el Estadio Santa Laura, con el fin que la hinchada meta presi\u00f3n durante la disputa de un complicado grupo para el cuadro m\u00e1gico.<\/strong><\/p>\n<p>Para el \u2018Fantasista\u2019 tener a los hinchas cerca en un reducto chico, a diferencia del Estadio Nacional, aparece como una clara ventaja para enfrentar a Cruzeiro de Brasil, Racing de Argentina y un clasificado de la fase previa, que saldr\u00e1 de la llave entre Vasco da Gama y Jorge Wilstermann.<\/p>\n<p>\u201cNosotros queremos jugar este tipo de partidos en estadios chicos, que metan presi\u00f3n de nuestra gente, para nosotros ser\u00eda ideal poder jugarla en Santa Laura\u2026Para este tipo de partidos, lo que significan los rivales que vamos a enfrentar, el rol que juega el hincha es muy importante\u201d, asegur\u00f3 en di\u00e1logo con Radio ADN.<\/p>\n<p>\u201cEl grupo es bastante complejo, con rivales de mucha categor\u00eda, los equipos, por lo que hemos visto, los equipos brasile\u00f1os y argentinos se han reforzado de manera importante para ganar la Libertadores. Pero nosotros, m\u00e1s all\u00e1 de lo que son nuestros mercados, futbol\u00edsticamente tenemos que estar preparado para competir ese tipo de situaciones, sobre todo porque se va a estadios importantes donde la local\u00eda es muy importante y tenemos que tener eso en consideraci\u00f3n\u201d, agreg\u00f3.<\/p>\n<p>Por otro lado, Pizarro espera ser protagonista en el andamiaje de Hoyos en la Copa, certamen donde la \u2018U\u2019 busca estar en las fases finales. \u201cCuando volv\u00ed a Chile tuve una infinidad de lesiones que me llevaron a hacerme muchas preguntas, pero el hecho de haber hecho una pretemporada bastante dura, ayud\u00f3 a ponerme a disposici\u00f3n desde el minuto uno\u00bb, sentenci\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>David Pizarro manifest\u00f3 su deseo que el cuadro azul sea local durante la Copa Libertadores 2018 en el Estadio Santa Laura, con el fin que la hinchada meta presi\u00f3n durante la disputa de un complicado grupo para el cuadro m\u00e1gico. Para el \u2018Fantasista\u2019 tener a los hinchas cerca en un reducto chico, a diferencia del [&#8230;]<\/p>\n","protected":false},"author":21398,"featured_media":13350,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[454,128,1116,111,156],"class_list":{"0":"post-13887","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"tag-actualidad","9":"tag-copa-libertadores","10":"tag-cuadro-magico","11":"tag-david-pizarro","12":"tag-universidad-de-chile"},"_links":{"self":[{"href":"https:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/13887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/users\/21398"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/comments?post=13887"}],"version-history":[{"count":1,"href":"https:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/13887\/revisions"}],"predecessor-version":[{"id":13888,"href":"https:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/posts\/13887\/revisions\/13888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/media\/13350"}],"wp:attachment":[{"href":"https:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/media?parent=13887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/categories?post=13887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rincondelbulla.cl\/portal\/wp-json\/wp\/v2\/tags?post=13887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}